{"id":1493,"date":"2026-04-23T23:40:42","date_gmt":"2026-04-23T23:40:42","guid":{"rendered":"https:\/\/latinosentinel.com\/?p=1493"},"modified":"2026-04-24T00:08:40","modified_gmt":"2026-04-24T00:08:40","slug":"arrestados-43-pandilleros-de-la-mafia-mexicana-sona-cusados-de-crimen-organizado-narcotrafico-secuestro-agresion-y-asesinato","status":"publish","type":"post","link":"https:\/\/latinosentinel.com\/en\/california\/arrestados-43-pandilleros-de-la-mafia-mexicana-sona-cusados-de-crimen-organizado-narcotrafico-secuestro-agresion-y-asesinato\/","title":{"rendered":"Arrestados 43 pandilleros de la Mafia Mexicana son acusados de crimen organizado, narcotr\u00e1fico, secuestro, agresi\u00f3n y asesinato"},"content":{"rendered":"<p><strong>Operaban su propio \u00abpara\u00edso pandillero\u00bb (*Gangsta\u2019s Paradise*) en el condado de Orange, mediante la venta de drogas il\u00edcitas y la perpetraci\u00f3n de agresiones y asesinatos, entre otros delitos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily.jpg\" alt=\"\" class=\"wp-image-1498\" srcset=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily.jpg 1280w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily-300x169.jpg 300w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily-1024x576.jpg 1024w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily-768x432.jpg 768w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/bill-essaily-18x10.jpg 18w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure>\n\n\n\n<p><strong><em>\u00abLos pandilleros que asesinan, extorsionan, secuestran y trafican drogas y armas de fuego representan una amenaza para nuestras comunidades y nuestro estilo de vida\u00bb, declar\u00f3 el primer fiscal federal adjunto, Bill Essayli.<\/em><\/strong><\/p>\n\n\n\n<p><strong>SANTA ANA, California<\/strong>. Veinticinco miembros y asociados de la Mexican Mafia \u2014una pandilla carcelaria\u2014, de un total de 43 acusados \u200b\u200bbajo custodia, fueron arrestados en virtud de tres acusaciones formales federales que les imputan la comisi\u00f3n de decenas de delitos en el condado de Orange; entre ellos se incluyen secuestro, extorsi\u00f3n, tr\u00e1fico de fentanilo y metanfetamina, gesti\u00f3n de negocios de apuestas ilegales y el asesinato de una v\u00edctima el a\u00f1o pasado en un motel de Anaheim controlado por la pandilla.<\/p>\n\n\n\n<p>Entre los acusados arrestados el jueves 23 de abril se encuentran:<\/p>\n\n\n\n<p>Jaime Alvarado, de 42 a\u00f1os, alias \u00abJunior\u00bb y \u00abBrian Barbas\u00bb, de Lake Elsinore;<\/p>\n\n\n\n<p>Karina Cesena, de 32 a\u00f1os, tambi\u00e9n de Lake Elsinore; y<\/p>\n\n\n\n<p>Mario Flores, de 40 a\u00f1os, alias \u00abHappy\u00bb, de Anaheim.<\/p>\n\n\n\n<p>Otros miembros de alto rango de la pandilla ya se encuentran bajo custodia estatal, entre ellos: Luis C\u00e1rdenas, de 48 a\u00f1os, alias \u00abGangster\u00bb, \u00abPops\u00bb y \u00abT\u00edo\u00bb, recluso en la Prisi\u00f3n Estatal de Ironwood;<\/p>\n\n\n\n<p>Jos\u00e9 Antonio Ochoa Madrigal, de 41 a\u00f1os, alias \u00abSparky\u00bb, de Santa Ana, quien se encuentra encarcelado en una prisi\u00f3n del condado de Orange.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-1024x768.jpg\" alt=\"\" class=\"wp-image-1506\" srcset=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-1024x768.jpg 1024w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-300x225.jpg 300w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-768x576.jpg 768w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-1536x1152.jpg 1536w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1-16x12.jpg 16w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-GANGSTA-OC-1.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>\u00abLos pandilleros que asesinan, extorsionan, secuestran y trafican drogas y armas de fuego representan una amenaza para nuestras comunidades y nuestro estilo de vida\u00bb, declar\u00f3 el primer fiscal federal adjunto, Bill Essayli. \u00abLos arrestos de hoy ponen de relieve la continua cooperaci\u00f3n entre las fuerzas del orden federales y locales en la lucha contra los delincuentes violentos, as\u00ed como nuestra inquebrantable determinaci\u00f3n de combatir el crimen organizado tanto en nuestras prisiones como en nuestras calles\u00bb.<\/p>\n\n\n\n<p>&nbsp;\u00abLos acusados \u200b\u200bde operar su propio &#8220;Gangsta\u2019s Paradise&#8221; en el Condado de Orange \u2014mediante la venta de drogas il\u00edcitas y la comisi\u00f3n de agresiones y asesinatos, entre otros delitos\u2014 est\u00e1n rindiendo cuentas ante la justicia hoy\u00bb, declar\u00f3 Akil Davis, director adjunto a cargo de la Oficina de Campo del FBI en Los \u00c1ngeles.<\/p>\n\n\n\n<p>\u00abLas comunidades del Condado de Orange deben sentirse orgullosas de sus profesionales de las fuerzas del orden, cuyo arduo trabajo y dedicaci\u00f3n a este caso han hecho que las calles del Condado de Orange sean hoy m\u00e1s seguras\u00bb.<\/p>\n\n\n\n<p>\u00abEste tipo de actividad delictiva tiene un impacto directo en nuestros vecindarios y en nuestros residentes\u00bb, afirm\u00f3 el jefe de Polic\u00eda de Anaheim, Manny Cid. \u00abMediante s\u00f3lidas alianzas, continuaremos identificando, desarticulando y haciendo rendir cuentas a los responsables\u00bb.<\/p>\n\n\n\n<p>\u00abEstas detenciones env\u00edan un mensaje claro: el crimen organizado y la violencia no ser\u00e1n tolerados en Santa Ana\u00bb, asegur\u00f3 el jefe de Polic\u00eda de Santa Ana, Robert Rodr\u00edguez. \u00abA trav\u00e9s de s\u00f3lidas alianzas con nuestras contrapartes locales y federales, seguiremos persiguiendo a aquellos que amenazan la seguridad y el bienestar de nuestras comunidades\u00bb.<\/p>\n\n\n\n<p>Quince de los detenidos comparecieron por primera vez ante el tribunal y fueron instruidos de cargos esta tarde en el Tribunal de Distrito de los Estados Unidos en Santa Ana. Diez de los detenidos fueron acusados ante el Tribunal de Distrito de los Estados Unidos en Los \u00c1ngeles. Otros doce acusados se encuentran bajo custodia estatal y se espera que comparezcan por primera vez ante el Tribunal de Distrito de los Estados Unidos en Santa Ana en las pr\u00f3ximas semanas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1-1024x576.jpg\" alt=\"\" class=\"wp-image-1508\" srcset=\"https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1-1024x576.jpg 1024w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1-300x169.jpg 300w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1-768x432.jpg 768w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1-18x10.jpg 18w, https:\/\/latinosentinel.com\/wp-content\/uploads\/2026\/04\/PANDILLEROS-DE-LA-EME-1.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>En relaci\u00f3n con esta investigaci\u00f3n, las fuerzas del orden han incautado 4 kilogramos (8,8 libras) de fentanilo, 54,4 kilogramos (120 libras) de metanfetamina, 0,9 kilogramos (2 libras) de hero\u00edna, 3 kilogramos (6,6 libras) de coca\u00edna, 25 armas de fuego y m\u00e1s de 30.000 d\u00f3lares en efectivo.<\/p>\n\n\n\n<p>La Mexican Mafia, tambi\u00e9n conocida como \u00abLa Eme\u00bb, es una pandilla carcelaria con sede en los Estados Unidos que ejerce un control inmenso sobre las pandillas callejeras hispanas en el sur de California, dirigiendo actividades il\u00edcitas desde las prisiones y cobrando una parte de las ganancias provenientes del narcotr\u00e1fico, las apuestas ilegales y otros delitos cometidos en las calles.<\/p>\n\n\n\n<p>La acusaci\u00f3n formal principal del caso imputa a 40 acusados de una serie de delitos graves, que incluyen conspiraci\u00f3n para delinquir (racketeering), conspiraci\u00f3n para operar un negocio de apuestas ilegales, delitos violentos en apoyo a actividades delictivas organizadas, tr\u00e1fico de narc\u00f3ticos \u2014tales como fentanilo, metanfetamina, hero\u00edna y coca\u00edna\u2014 y el uso de armas de fuego durante la comisi\u00f3n de un delito violento. Seg\u00fan esta acusaci\u00f3n formal de 66 cargos, desde junio de 2024 hasta abril de 2026, C\u00e1rdenas supervis\u00f3 las actividades delictivas de la Mexican Mafia en el condado de Orange, as\u00ed como en las c\u00e1rceles y centros penitenciarios de dicho condado. Alvarado, Cesena, Madrigal y Flores ocupaban cargos de alto rango como asociados bajo el mando de C\u00e1rdenas.<\/p>\n\n\n\n<p>Desde su celda en prisi\u00f3n, C\u00e1rdenas utiliz\u00f3 una aplicaci\u00f3n de mensajer\u00eda encriptada en tel\u00e9fonos celulares de contrabando para dar instrucciones a Alvarado sobre la operaci\u00f3n de las actividades de la Mexican Mafia en el condado de Orange.<\/p>\n\n\n\n<p>C\u00e1rdenas orden\u00f3 a otros secuestrar y agredir a personas que estaban enemistadas con \u00e9l; Alvarado, Cesena y otros cumplieron sus \u00f3rdenes. Los acusados, que operaban para la Mexican Mafia, dispararon contra las v\u00edctimas y las agredieron.<\/p>\n\n\n\n<p>La pandilla tambi\u00e9n vend\u00eda narc\u00f3ticos \u2014incluyendo fentanilo, metanfetamina, hero\u00edna y coca\u00edna\u2014 a trav\u00e9s de *slap houses* (casas de juego ilegales), otras pandillas y traficantes de drogas en el condado de Orange.<\/p>\n\n\n\n<p>Gestionaba negocios de juego ilegal dentro de centros comerciales y residencias privadas. La pandilla cobraba impuestos extorsivos y proporcionaba seguridad \u2014incluyendo el uso de la violencia\u2014 para proteger dichos negocios de juego ilegal.<\/p>\n\n\n\n<p>Alvarado supervisaba los moteles controlados por la pandilla y, junto con Cesena, dirig\u00eda represalias violentas contra las *slap houses* que no pagaban los extorsivos &#8220;impuestos&#8221; de la pandilla.<\/p>\n\n\n\n<p>El 3 de febrero de 2025, Matthew Kundrat, de 29 a\u00f1os \u2014alias &#8220;Bubba&#8221;\u2014, de Anaheim, y Manuel Ramos, de 45 a\u00f1os \u2014alias &#8220;Rhino&#8221;\u2014, de Santa Ana, asesinaron a una v\u00edctima en el Akua Inn, un motel controlado por la pandilla en Anaheim. Kundrat y Ramos cometieron el asesinato con el prop\u00f3sito de ser admitidos en la Mexican Mafia y mejorar su estatus dentro de la organizaci\u00f3n criminal.<\/p>\n\n\n\n<p>Tanto Kundrat como Ramos est\u00e1n acusados \u200b\u200bde cometer un delito violento en apoyo a actividades de crimen organizado (*racketeering*); de ser declarados culpables, enfrentar\u00edan una sentencia obligatoria de cadena perpetua en una prisi\u00f3n federal y podr\u00edan ser elegibles para la pena de muerte.<\/p>\n\n\n\n<p>El 14 de marzo de 2025, C\u00e1rdenas, Alvarado, Flores y Cesena ordenaron el secuestro y la agresi\u00f3n de una v\u00edctima que trabajaba como empleado en una *slap house* controlada por C\u00e1rdenas en Stanton. La pena por secuestro es la cadena perpetua en una prisi\u00f3n federal.<\/p>\n\n\n\n<p>Alvarado y Cesena almacenaban metanfetamina y armas de fuego en una unidad de almacenamiento en el condado de Orange, as\u00ed como en residencias privadas locales.<\/p>\n\n\n\n<p>&#8220;Cuando las organizaciones criminales intentan ocultar sus ganancias detr\u00e1s de la violencia, la intimidaci\u00f3n y complejas redes basadas en el uso de efectivo, la Divisi\u00f3n de Investigaci\u00f3n Criminal del IRS sacar\u00e1 a la luz la verdad&#8221;, declar\u00f3 Darren Lian, Agente Especial Encargado Interino de la Oficina de Campo de Los \u00c1ngeles de la Divisi\u00f3n de Investigaci\u00f3n Criminal del IRS.<\/p>\n\n\n\n<p>\u00abNuestros agentes siguieron el rastro del dinero a trav\u00e9s de los ingresos provenientes del narcotr\u00e1fico, esquemas de extorsi\u00f3n y operaciones de juego ilegal que alimentaban el poder de esta organizaci\u00f3n. Al rastrear y desmantelar estos canales financieros, asestamos un golpe directo a la capacidad operativa de la organizaci\u00f3n. La Divisi\u00f3n de Investigaci\u00f3n Criminal del IRS (IRS CI) mantiene su compromiso de proteger a nuestras comunidades atacando la infraestructura financiera que sustenta al crimen organizado, sin importar cu\u00e1n profundamente arraigada se encuentre\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Operaban su propio \u00abpara\u00edso pandillero\u00bb (*Gangsta\u2019s Paradise*) en el condado de Orange, mediante la venta de drogas il\u00edcitas y la perpetraci\u00f3n de agresiones y asesinatos, entre otros delitos. \u00abLos pandilleros&hellip; <\/p>","protected":false},"author":2,"featured_media":1498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,51],"tags":[31,281,130,272,280,282,283],"class_list":["post-1493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-california","category-estados-unidos","tag-asesinato","tag-crimen-organizado","tag-fbi","tag-la-eme","tag-mafia-mexicana","tag-narcotrafico","tag-pandilleros"],"_links":{"self":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts\/1493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/comments?post=1493"}],"version-history":[{"count":6,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts\/1493\/revisions"}],"predecessor-version":[{"id":1511,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts\/1493\/revisions\/1511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/media\/1498"}],"wp:attachment":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/media?parent=1493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/categories?post=1493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/tags?post=1493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}