{"id":337,"count":1,"description":"","link":"https:\/\/latinosentinel.com\/en\/etiquetas\/matt-maham\/","name":"Matt Maham","slug":"matt-maham","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/tags\/337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts?tags=337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}