{"id":350,"count":1,"description":"","link":"https:\/\/latinosentinel.com\/en\/etiquetas\/lavado-de-dinero\/","name":"lavado de dinero","slug":"lavado-de-dinero","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/tags\/350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/latinosentinel.com\/en\/wp-json\/wp\/v2\/posts?tags=350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}